{"id":2550,"date":"2020-11-27T09:42:21","date_gmt":"2020-11-27T09:42:21","guid":{"rendered":"https:\/\/bbr.ch\/?p=2550"},"modified":"2020-11-27T09:42:22","modified_gmt":"2020-11-27T09:42:22","slug":"ein-beruf-mit-zukunft-sefa-oeszarslan-erzaehlt-von-seiner-lehrstelle-bei-uns","status":"publish","type":"post","link":"https:\/\/bbr.ch\/fr\/ein-beruf-mit-zukunft-sefa-oeszarslan-erzaehlt-von-seiner-lehrstelle-bei-uns\/","title":{"rendered":"Un m\u00e9tier d'avenir : Sefa Oeszarslan nous parle de son apprentissage !"},"content":{"rendered":"<p>Sefa termine son apprentissage avec nous en tant que recycleur chez FA\/CFC et en est \u00e0 sa 3\u00e8me ann\u00e9e de formation. La raison pour laquelle il a choisi ce m\u00e9tier peut sembler laconique, mais elle prend tout son sens dans la suite de la conversation : Au d\u00e9but, Sefa ne savait m\u00eame pas quelle formation il devait suivre. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"750\" height=\"417\" src=\"https:\/\/bbr.ch\/wp-content\/uploads\/2020\/11\/IMG_0563.jpg\" alt=\"\" class=\"wp-image-2576\" srcset=\"https:\/\/bbr.ch\/wp-content\/uploads\/2020\/11\/IMG_0563.jpg 750w, https:\/\/bbr.ch\/wp-content\/uploads\/2020\/11\/IMG_0563-300x167.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p>Mais il aimait notre entreprise et les nombreuses machines. Il a \u00e9galement d\u00fb apprendre en priv\u00e9 comment trier et \u00e9liminer les d\u00e9chets. Il sait aujourd'hui ce qu'il advient d'un m\u00e9got de cigarette jet\u00e9 : un seul pollue 1m3<sup>3<\/sup>&nbsp;d'eau. Ils ont parl\u00e9 des jeunes du climat \u00e0 l'\u00e9cole et un professeur a dit : Ils devraient absolument manifester pour le climat, mais pour chaque heure pass\u00e9e \u00e0 la manifestation, ils devraient travailler dans une entreprise de recyclage. <\/p>\n\n\n\n<p>Sefa pense \u00e0 notre environnement, sans la jeunesse du climat mais dans son travail quotidien. Et ce qu'il voit le fait r\u00e9fl\u00e9chir : il pense qu'il est trop tard pour sauver l'environnement, mais que nous pouvons contribuer activement et \u00e9nergiquement \u00e0 retarder la poursuite de la pollution - et donc \u00e0 prolonger l'avenir.<br><br>Il aime particuli\u00e8rement faire fonctionner les machines. Un apprenti peut faire fonctionner une excavatrice avec un bras de pr\u00e9hension ou conduire un chariot \u00e9l\u00e9vateur \u00e0 fourche en \u00abapprenant par la pratique\u00bb. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/bbr.ch\/wp-content\/uploads\/2020\/11\/IMG_0453-Kopie-1024x768.jpg\" alt=\"\" class=\"wp-image-2572\" srcset=\"https:\/\/bbr.ch\/wp-content\/uploads\/2020\/11\/IMG_0453-Kopie-1024x768.jpg 1024w, https:\/\/bbr.ch\/wp-content\/uploads\/2020\/11\/IMG_0453-Kopie-300x225.jpg 300w, https:\/\/bbr.ch\/wp-content\/uploads\/2020\/11\/IMG_0453-Kopie-768x576.jpg 768w, https:\/\/bbr.ch\/wp-content\/uploads\/2020\/11\/IMG_0453-Kopie.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Si tout se passe bien, Sefa terminera son apprentissage avec un certificat de sp\u00e9cialiste en mai\/juin 2021. Apr\u00e8s cela, il aimerait bien obtenir son certificat de camionneur, car il s'int\u00e9resse aussi \u00e0 la logistique.\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>Le recyclage avec certificat f\u00e9d\u00e9ral de capacit\u00e9 est un apprentissage de trois ans qui peut \u00e9galement \u00eatre effectu\u00e9 chez nous : Une profession d'avenir ! <\/p>","protected":false},"author":1,"featured_media":2575,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[25,40],"tags":[],"class_list":["post-2550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mitarbeitende","category-lehrbetrieb"],"acf":[],"_links":{"self":[{"href":"https:\/\/bbr.ch\/fr\/wp-json\/wp\/v2\/posts\/2550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bbr.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bbr.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bbr.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bbr.ch\/fr\/wp-json\/wp\/v2\/comments?post=2550"}],"version-history":[{"count":6,"href":"https:\/\/bbr.ch\/fr\/wp-json\/wp\/v2\/posts\/2550\/revisions"}],"predecessor-version":[{"id":2578,"href":"https:\/\/bbr.ch\/fr\/wp-json\/wp\/v2\/posts\/2550\/revisions\/2578"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bbr.ch\/fr\/wp-json\/wp\/v2\/media\/2575"}],"wp:attachment":[{"href":"https:\/\/bbr.ch\/fr\/wp-json\/wp\/v2\/media?parent=2550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bbr.ch\/fr\/wp-json\/wp\/v2\/categories?post=2550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bbr.ch\/fr\/wp-json\/wp\/v2\/tags?post=2550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}